{"id":159,"date":"2017-08-09T10:09:38","date_gmt":"2017-08-09T10:09:38","guid":{"rendered":"https:\/\/proenergiessa.com\/index.php\/home\/"},"modified":"2022-10-14T18:07:03","modified_gmt":"2022-10-14T18:07:03","slug":"home","status":"publish","type":"page","link":"https:\/\/proenergiessa.com\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"159\" class=\"elementor elementor-159\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66f558a elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"66f558a\" data-element_type=\"section\" id=\"home\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f086803\" data-id=\"f086803\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64425bc elementor-widget elementor-widget-spacer\" data-id=\"64425bc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-container{--container-widget-width:100%}.e-container>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));-ms-flex-item-align:stretch;align-self:stretch;-ms-flex-negative:0;flex-shrink:0}.e-container>.elementor-widget-spacer>.elementor-widget-container,.e-container>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-container>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81345be elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81345be\" data-element_type=\"section\" id=\"about\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;curve-asymmetrical&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,0c0,0,0,6,0,6.7c0,18,240.2,93.6,615.2,92.6C989.8,98.5,1000,25,1000,6.7c0-0.7,0-6.7,0-6.7H0z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fead32\" data-id=\"6fead32\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa7661d elementor-widget elementor-widget-image\" data-id=\"aa7661d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"853\" height=\"537\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/Capture-decran-11-012534.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/Capture-decran-11-012534.png 853w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/Capture-decran-11-012534-300x189.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/Capture-decran-11-012534-768x483.png 768w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b104985\" data-id=\"b104985\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69e24cb elementor-widget elementor-widget-heading\" data-id=\"69e24cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">About the foundation<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e526cc7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e526cc7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#2c2c2c;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);-ms-flex-negative:0;flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:-webkit-box;display:-ms-flexbox;display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{-webkit-box-flex:0;-ms-flex-positive:0;flex-grow:0;-ms-flex-negative:100;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{-webkit-box-flex:0;-ms-flex-positive:0;flex-grow:0;-ms-flex-negative:100;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-container>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow,0)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-851c581 elementor-widget elementor-widget-text-editor\" data-id=\"851c581\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-443\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-300x300.png\" alt=\"\" width=\"19\" height=\"19\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right.png 512w\" sizes=\"(max-width: 19px) 100vw, 19px\" \/>\u00a0\u00a0<span style=\"font-style: inherit; font-weight: inherit; color: var(--ast-global-color-3);\">A leading provider of spare parts, faucets and filters services focused on providing business solutions in gas, petrochemicals, environment, railways, transportation and manufacturing in the Kingdom of Saudi Arabia and the Gulf region.<\/span><\/p><p><span style=\"font-style: inherit; font-weight: inherit; color: var(--ast-global-color-3);\"><img loading=\"lazy\" class=\"alignnone wp-image-443\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-300x300.png\" alt=\"\" width=\"19\" height=\"19\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right.png 512w\" sizes=\"(max-width: 19px) 100vw, 19px\" \/>\u00a0We provide professional services with new technology with high standards that guarantee excellence, innovation and customer satisfaction in his field of specialization.<\/span><\/p><p><span style=\"font-style: inherit; font-weight: inherit; color: var(--ast-global-color-3);\"> <img loading=\"lazy\" class=\"alignnone wp-image-443\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-300x300.png\" alt=\"\" width=\"19\" height=\"19\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right.png 512w\" sizes=\"(max-width: 19px) 100vw, 19px\" \/>\u00a0 The company consists of several main divisions, namely industrial supplies, services, projects, warehousing and joint ventures.<\/span><\/p><p><span style=\"font-style: inherit; font-weight: inherit; color: var(--ast-global-color-3);\"><img loading=\"lazy\" class=\"alignnone wp-image-443\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-300x300.png\" alt=\"\" width=\"19\" height=\"19\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/arrow-right.png 512w\" sizes=\"(max-width: 19px) 100vw, 19px\" \/> \u00a0 These departments collaborate either together to implement projects or independently to implement projects in their respective disciplines.<\/span><\/p><p><span style=\"font-style: inherit; font-weight: inherit; color: var(--ast-global-color-3);\"> Considering experience, expertise, financial resources and equipment, we are able and confident to undertake any project related to our huge business portfolio.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ifc4ej9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ifc4ej9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d908984\" data-id=\"d908984\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a0a173 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a0a173\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6e1a6b1\" data-id=\"6e1a6b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96f1f18 elementor-widget elementor-widget-heading\" data-id=\"96f1f18\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our values<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fb35ae elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2fb35ae\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cfc2260 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfc2260\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3d2fa9f\" data-id=\"3d2fa9f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c92e2e4 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"c92e2e4\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;-webkit-box-orient:horizontal;-webkit-box-direction:reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;-webkit-box-orient:horizontal;-webkit-box-direction:normal;-ms-flex-direction:row;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{-webkit-box-align:start;-ms-flex-align:start;align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{-webkit-box-align:center;-ms-flex-align:center;align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{-webkit-box-align:end;-ms-flex-align:end;align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"512\" height=\"512\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/target.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Professionalism<\/h5><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64d89d2 elementor-widget elementor-widget-text-editor\" data-id=\"64d89d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We believe that a professional approach will get us to our Vision.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-877fd22\" data-id=\"877fd22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d1df20 elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"4d1df20\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"400\" height=\"400\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/customerIcon.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Customer Centric<\/h5><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16927db elementor-widget elementor-widget-text-editor\" data-id=\"16927db\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">We always keep in mind our customers while taking up any initiatives with an objective of providing them with constructions service of a very high class.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-abbd948\" data-id=\"abbd948\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f02551a elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"f02551a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img width=\"512\" height=\"512\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/worker.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Team <br>Work<\/h5><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8179dfb elementor-widget elementor-widget-text-editor\" data-id=\"8179dfb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We encourage everyone to share information and ideas regardless of status, education, ethnicity or religion.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-prv14b4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"prv14b4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e4c592\" data-id=\"4e4c592\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81b42e4 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"81b42e4\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">vision<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ca1df4 elementor-widget elementor-widget-text-editor\" data-id=\"6ca1df4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Our vision serves as the frame work for our roadmap and guide every aspects of our business by describing what we need to accomplish in order to continue achieving sustainable quality growth, to be the best contractor and employer of choice by safely &amp; consistently delivering successful and innovation capital projects and services in the kingdom of Saudi Arabia.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2f4a09\" data-id=\"a2f4a09\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b83592e elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"b83592e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">mision<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7337530 elementor-widget elementor-widget-text-editor\" data-id=\"7337530\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\">Our roadmap starts with our mission which is enduring, it declares our purpose as a company and serve as the standard against which we weigh our action and decisions.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34da0ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34da0ca\" data-element_type=\"section\" id=\"training\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_top&quot;:&quot;curve-asymmetrical&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M615.2,96.7C240.2,97.8,0,18.9,0,0v100h1000V0C1000,19.2,989.8,96,615.2,96.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4c0048\" data-id=\"a4c0048\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74e4b1c elementor-widget elementor-widget-heading\" data-id=\"74e4b1c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-family: Roboto, sans-serif; font-size: 3rem; text-align: center; white-space: normal;\">SERVICES<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b63118c elementor-widget-mobile__width-inherit elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b63118c\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3df6215 elementor-widget elementor-widget-spacer\" data-id=\"3df6215\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-797ba04 elementor-widget elementor-widget-image\" data-id=\"797ba04\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/elementor\/thumbs\/link-pw29zdxxrosfrgzvjdr2nhjikhqfkhsv19jk6nk8io.png\" title=\"link\" alt=\"link\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0004e2c elementor-widget elementor-widget-heading\" data-id=\"0004e2c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Supply chain management<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1edd4fb elementor-widget elementor-widget-text-editor\" data-id=\"1edd4fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><img loading=\"lazy\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-300x300.png\" alt=\"\" width=\"20\" height=\"20\" \/> Pro Energies uses its resources around the globe to procure all the industrial equipment, spares, supplies and deliver to the client&#8217;s location.<\/p><p><img loading=\"lazy\" class=\"alignnone  wp-image-356\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-300x300.png\" alt=\"\" width=\"21\" height=\"21\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec.png 512w\" sizes=\"(max-width: 21px) 100vw, 21px\" \/>\u00a0With the support of our Sister company Altarss Trading, we manage to give a comprehensive supply solution to our client.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61a1b62 elementor-widget elementor-widget-image\" data-id=\"61a1b62\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/elementor\/thumbs\/worker-1-pw1vyrb6xfqz3hmo3jaqyjlhtztrwo3qhxzb83vizs.png\" title=\"worker (1)\" alt=\"worker (1)\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a24cbb elementor-widget elementor-widget-heading\" data-id=\"6a24cbb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">industrial services<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fcd4fe elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0fcd4fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-356\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-300x300.png\" alt=\"\" width=\"20\" height=\"20\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>\u00a0 Provides extensive and specialized industrial services.<br \/><img loading=\"lazy\" class=\"alignnone wp-image-356\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-300x300.png\" alt=\"\" width=\"20\" height=\"20\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec.png 512w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>\u00a0 We deploys a high caliber of engineers to manage its projects with a workforce that is capable of executing specialized engineering work.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bce6ec elementor-widget elementor-widget-image\" data-id=\"2bce6ec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/elementor\/thumbs\/discussion-pw3m8wlv9j2v9ysaj7sl58v9j2khsy9t3ji7edf6qw.png\" title=\"discussion\" alt=\"discussion\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1639c04 elementor-widget elementor-widget-heading\" data-id=\"1639c04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">business consultancy<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2581e9d elementor-widget elementor-widget-text-editor\" data-id=\"2581e9d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><img loading=\"lazy\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/rec-300x300.png\" alt=\"\" width=\"20\" height=\"20\" \/>\u00a0 Provides consultancy for the international companies for business setups and support them for execution of project through arranging required resources, Also do authorized representation.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c96319a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c96319a\" data-element_type=\"section\" id=\"gallery\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;curve-asymmetrical&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;,&quot;shape_divider_bottom&quot;:&quot;curve-asymmetrical&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M615.2,96.7C240.2,97.8,0,18.9,0,0v100h1000V0C1000,19.2,989.8,96,615.2,96.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M615.2,96.7C240.2,97.8,0,18.9,0,0v100h1000V0C1000,19.2,989.8,96,615.2,96.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d7a298\" data-id=\"5d7a298\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-556d013 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"556d013\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Products<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5de04c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a5de04c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca0fb21 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"ca0fb21\" data-element_type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-wrapper{width:25%;-ms-flex-negative:0;flex-shrink:0}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active{border-right-style:none}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:before{height:999em;width:0;right:0;border-right-style:solid}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:before{top:0;-webkit-transform:translateY(-100%);-ms-transform:translateY(-100%);transform:translateY(-100%)}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tab-desktop-title.elementor-active:after{top:100%}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title{display:table-cell}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active{border-bottom-style:none}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:before{bottom:0;height:0;width:999em;border-bottom-style:solid}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:before{right:100%}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-desktop-title.elementor-active:after{left:100%}.elementor-widget-tabs .elementor-tab-content,.elementor-widget-tabs .elementor-tab-title,.elementor-widget-tabs .elementor-tab-title:after,.elementor-widget-tabs .elementor-tab-title:before,.elementor-widget-tabs .elementor-tabs-content-wrapper{border:1px #d4d4d4}.elementor-widget-tabs .elementor-tabs{text-align:left}.elementor-widget-tabs .elementor-tabs-wrapper{overflow:hidden}.elementor-widget-tabs .elementor-tab-title{cursor:pointer;outline:var(--focus-outline,none)}.elementor-widget-tabs .elementor-tab-desktop-title{position:relative;padding:20px 25px;font-weight:700;line-height:1;border:solid transparent}.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active{border-color:#d4d4d4}.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active:after,.elementor-widget-tabs .elementor-tab-desktop-title.elementor-active:before{display:block;content:\"\";position:absolute}.elementor-widget-tabs .elementor-tab-desktop-title:focus-visible{border:1px solid #000}.elementor-widget-tabs .elementor-tab-mobile-title{padding:10px;cursor:pointer}.elementor-widget-tabs .elementor-tab-content{padding:20px;display:none}@media (max-width:767px){.elementor-tabs .elementor-tab-content,.elementor-tabs .elementor-tab-title{border-style:solid solid none}.elementor-tabs .elementor-tabs-wrapper{display:none}.elementor-tabs .elementor-tabs-content-wrapper{border-bottom-style:solid}.elementor-tabs .elementor-tab-content{padding:10px}}@media (min-width:768px){.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-wrapper{-webkit-box-orient:vertical;-webkit-box-direction:normal;-ms-flex-direction:column;flex-direction:column}.elementor-widget-tabs.elementor-tabs-view-vertical .elementor-tabs-content-wrapper{-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1;border-style:solid solid solid none}.elementor-widget-tabs.elementor-tabs-view-horizontal .elementor-tab-content{border-style:none solid solid}.elementor-widget-tabs.elementor-tabs-alignment-center .elementor-tabs-wrapper,.elementor-widget-tabs.elementor-tabs-alignment-end .elementor-tabs-wrapper,.elementor-widget-tabs.elementor-tabs-alignment-stretch .elementor-tabs-wrapper{display:-webkit-box;display:-ms-flexbox;display:flex}.elementor-widget-tabs.elementor-tabs-alignment-center .elementor-tabs-wrapper{-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center}.elementor-widget-tabs.elementor-tabs-alignment-end .elementor-tabs-wrapper{-webkit-box-pack:end;-ms-flex-pack:end;justify-content:flex-end}.elementor-widget-tabs.elementor-tabs-alignment-stretch.elementor-tabs-view-horizontal .elementor-tab-title{width:100%}.elementor-widget-tabs.elementor-tabs-alignment-stretch.elementor-tabs-view-vertical .elementor-tab-title{height:100%}.elementor-tabs .elementor-tab-mobile-title{display:none}}<\/style>\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2111\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2111\" aria-expanded=\"false\">Maintenance Materiels<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2112\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2112\" aria-expanded=\"false\">Filters<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2113\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2113\" aria-expanded=\"false\">Tools<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2114\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2114\" aria-expanded=\"false\">Spare Parts<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2115\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2115\" aria-expanded=\"false\">Pumps<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-2116\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2116\" aria-expanded=\"false\">Hoses<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-2111\" aria-expanded=\"false\">Maintenance Materiels<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2111\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2111\" tabindex=\"0\" hidden=\"false\"><p style=\"text-align: left;\"><img loading=\"lazy\" class=\"alignnone wp-image-369\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm1-1-298x300.png\" alt=\"\" width=\"148\" height=\"149\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm1-1-298x300.png 298w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm1-1-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm1-1.png 358w\" sizes=\"(max-width: 148px) 100vw, 148px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-370\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm2-300x300.png\" alt=\"\" width=\"148\" height=\"148\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm2-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm2-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm2.png 357w\" sizes=\"(max-width: 148px) 100vw, 148px\" \/>\u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" class=\"alignnone wp-image-371\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm3-292x300.png\" alt=\"\" width=\"145\" height=\"149\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm3-292x300.png 292w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm3.png 346w\" sizes=\"(max-width: 145px) 100vw, 145px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-372\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm4-298x300.png\" alt=\"\" width=\"148\" height=\"149\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm4-298x300.png 298w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm4-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm4.png 357w\" sizes=\"(max-width: 148px) 100vw, 148px\" \/>\u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-373\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm5-297x300.png\" alt=\"\" width=\"146\" height=\"148\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm5-297x300.png 297w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm5.png 351w\" sizes=\"(max-width: 146px) 100vw, 146px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-374\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm6-294x300.png\" alt=\"\" width=\"146\" height=\"149\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm6-294x300.png 294w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm6.png 357w\" sizes=\"(max-width: 146px) 100vw, 146px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<img loading=\"lazy\" class=\"alignnone wp-image-376\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm8-285x300.png\" alt=\"\" width=\"148\" height=\"156\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm8-285x300.png 285w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm8.png 366w\" sizes=\"(max-width: 148px) 100vw, 148px\" \/>\u00a0 \u00a0 \u00a0 \u00a0<img loading=\"lazy\" class=\"alignnone wp-image-377\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm9-261x300.png\" alt=\"\" width=\"129\" height=\"148\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm9-261x300.png 261w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/mm9.png 322w\" sizes=\"(max-width: 129px) 100vw, 129px\" \/><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2112\" aria-expanded=\"false\">Filters<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2112\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2112\" tabindex=\"0\" hidden=\"hidden\"><p style=\"text-align: left;\"><img loading=\"lazy\" class=\"alignnone wp-image-394\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f1-271x300.png\" alt=\"\" width=\"160\" height=\"177\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f1-271x300.png 271w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f1.png 303w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/>\u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-395\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f2-258x300.png\" alt=\"\" width=\"160\" height=\"186\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f2-258x300.png 258w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f2.png 292w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/>\u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-398\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f3-1-267x300.png\" alt=\"\" width=\"165\" height=\"186\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f3-1-267x300.png 267w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f3-1.png 300w\" sizes=\"(max-width: 165px) 100vw, 165px\" \/>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" class=\"alignnone wp-image-397\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f4-272x300.png\" alt=\"\" width=\"166\" height=\"184\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f4-272x300.png 272w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/f4.png 307w\" sizes=\"(max-width: 166px) 100vw, 166px\" \/>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2113\" aria-expanded=\"false\">Tools<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2113\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2113\" tabindex=\"0\" hidden=\"hidden\"><p style=\"text-align: center;\"><img loading=\"lazy\" class=\"alignnone wp-image-378\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n1-277x300.png\" alt=\"\" width=\"151\" height=\"163\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n1-277x300.png 277w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n1.png 339w\" sizes=\"(max-width: 151px) 100vw, 151px\" \/>\u00a0 \u00a0 \u00a0\u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-379\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n2-284x300.png\" alt=\"\" width=\"154\" height=\"163\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n2-284x300.png 284w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n2.png 345w\" sizes=\"(max-width: 154px) 100vw, 154px\" \/>\u00a0 \u00a0\u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-380\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n3-297x300.png\" alt=\"\" width=\"158\" height=\"160\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n3-297x300.png 297w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n3.png 360w\" sizes=\"(max-width: 158px) 100vw, 158px\" \/>\u00a0 \u00a0\u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-381\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n4-300x293.png\" alt=\"\" width=\"163\" height=\"159\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n4-300x293.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n4.png 375w\" sizes=\"(max-width: 163px) 100vw, 163px\" \/>\u00a0 \u00a0\u00a0 <img loading=\"lazy\" class=\"wp-image-382 alignleft\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n5-300x300.png\" alt=\"\" width=\"160\" height=\"160\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n5-300x300.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n5-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n5.png 367w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/> <img loading=\"lazy\" class=\"alignnone wp-image-383\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n6-287x300.png\" alt=\"\" width=\"158\" height=\"166\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n6-287x300.png 287w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n6.png 351w\" sizes=\"(max-width: 158px) 100vw, 158px\" \/>\u00a0 \u00a0\u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-384\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n7-260x300.png\" alt=\"\" width=\"158\" height=\"182\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n7-260x300.png 260w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n7.png 343w\" sizes=\"(max-width: 158px) 100vw, 158px\" \/>\u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-385\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n8-292x300.png\" alt=\"\" width=\"152\" height=\"156\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n8-292x300.png 292w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/n8.png 351w\" sizes=\"(max-width: 152px) 100vw, 152px\" \/>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2114\" aria-expanded=\"false\">Spare Parts<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2114\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2114\" tabindex=\"0\" hidden=\"hidden\"><p style=\"text-align: left;\"><img loading=\"lazy\" class=\"alignnone wp-image-404\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/1M-3-300x297.png\" alt=\"\" width=\"168\" height=\"166\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/1M-3-300x297.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/1M-3.png 367w\" sizes=\"(max-width: 168px) 100vw, 168px\" \/>\u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-405\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/2M-3-294x300.png\" alt=\"\" width=\"169\" height=\"173\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/2M-3-294x300.png 294w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/2M-3.png 364w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/> \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-406\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/3M-3-298x300.png\" alt=\"\" width=\"166\" height=\"167\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/3M-3-298x300.png 298w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/3M-3-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/3M-3.png 358w\" sizes=\"(max-width: 166px) 100vw, 166px\" \/>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" class=\"alignnone wp-image-407\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/4M-2-271x300.png\" alt=\"\" width=\"159\" height=\"176\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/4M-2-271x300.png 271w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/4M-2.png 331w\" sizes=\"(max-width: 159px) 100vw, 159px\" \/>\u00a0\u00a0<img loading=\"lazy\" class=\"alignnone wp-image-408\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/5M-2-300x298.png\" alt=\"\" width=\"169\" height=\"168\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/5M-2-300x298.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/5M-2-150x150.png 150w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/5M-2.png 379w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2115\" aria-expanded=\"false\">Pumps<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2115\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2115\" tabindex=\"0\" hidden=\"hidden\"><p style=\"text-align: left;\"><img loading=\"lazy\" class=\"alignnone wp-image-390\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p1-289x300.png\" alt=\"\" width=\"166\" height=\"173\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p1-289x300.png 289w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p1.png 348w\" sizes=\"(max-width: 166px) 100vw, 166px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-391\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p2-273x300.png\" alt=\"\" width=\"160\" height=\"176\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p2-273x300.png 273w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p2.png 336w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" class=\"alignnone wp-image-392\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p3-278x300.png\" alt=\"\" width=\"160\" height=\"172\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p3-278x300.png 278w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p3.png 340w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/><span style=\"font-size: 16px; text-align: center;\">\u00a0<\/span><img loading=\"lazy\" class=\"wp-image-393 alignleft\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p4-300x294.png\" alt=\"\" width=\"165\" height=\"162\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p4-300x294.png 300w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/p4.png 364w\" sizes=\"(max-width: 165px) 100vw, 165px\" \/><\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-2116\" aria-expanded=\"false\">Hoses<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2116\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2116\" tabindex=\"0\" hidden=\"hidden\"><p style=\"text-align: left;\"><img loading=\"lazy\" class=\"alignnone wp-image-386\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h1-276x300.png\" alt=\"\" width=\"142\" height=\"155\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h1-276x300.png 276w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h1.png 301w\" sizes=\"(max-width: 142px) 100vw, 142px\" \/>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" class=\"wp-image-387 alignnone\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h2-273x300.png\" alt=\"\" width=\"140\" height=\"154\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h2-273x300.png 273w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h2.png 295w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>\u00a0 \u00a0 <img loading=\"lazy\" class=\"alignnone wp-image-388\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h3-281x300.png\" alt=\"\" width=\"142\" height=\"151\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h3-281x300.png 281w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h3.png 310w\" sizes=\"(max-width: 142px) 100vw, 142px\" \/>\u00a0 \u00a0 \u00a0 <img loading=\"lazy\" class=\"wp-image-389 alignleft\" src=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h4-277x300.png\" alt=\"\" width=\"137\" height=\"148\" srcset=\"https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h4-277x300.png 277w, https:\/\/proenergiessa.com\/wp-content\/uploads\/2022\/10\/h4.png 297w\" sizes=\"(max-width: 137px) 100vw, 137px\" \/>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87645fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87645fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e8fab8\" data-id=\"2e8fab8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-qt81hjh elementor-section-content-middle elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"qt81hjh\" data-element_type=\"section\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e9f82fa\" data-id=\"e9f82fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5d023b elementor-widget elementor-widget-heading\" data-id=\"f5d023b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get In Touch With Us!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8366d53 elementor-widget elementor-widget-heading\" data-id=\"8366d53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-medium\">Phone<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8579f7 elementor-widget elementor-widget-text-editor\" data-id=\"c8579f7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t+ 1 234 567 890\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7b463f elementor-widget elementor-widget-heading\" data-id=\"b7b463f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-medium\">Email<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcacc78 elementor-widget elementor-widget-text-editor\" data-id=\"bcacc78\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>director@proenergiessa.com<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67a9c6d elementor-widget elementor-widget-heading\" data-id=\"67a9c6d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-medium\">Address<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad3206e elementor-widget elementor-widget-text-editor\" data-id=\"ad3206e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Dammam, Al Mohammediyah<br \/>District -Al Kamila.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e973bc4\" data-id=\"e973bc4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6327b04 elementor-widget elementor-widget-google_maps\" data-id=\"6327b04\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Dammam%2C%20Al%20Mohammediyah%2C%20Al%20Kamila&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Dammam, Al Mohammediyah, Al Kamila\"\n\t\t\t\t\taria-label=\"Dammam, Al Mohammediyah, Al Kamila\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-98b2402\" data-id=\"98b2402\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3791c59 elementor-widget elementor-widget-heading\" data-id=\"3791c59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Send a message<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9423e elementor-widget elementor-widget-shortcode\" data-id=\"5f9423e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container \" id=\"wpforms-38\"><form id=\"wpforms-form-38\" class=\"wpforms-validate wpforms-form\" data-formid=\"38\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/159\" data-token=\"135baf96c2c50465f89e9533977db03e\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-38-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-38-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-38-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Name\" required><\/div><div id=\"wpforms-38-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-38-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-38-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Email\" required><\/div><div id=\"wpforms-38-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-38-field_3\">Subject <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-38-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"Subject\" required><\/div><div id=\"wpforms-38-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-38-field_2\">Comment or Message <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-38-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Message\" required><\/textarea><\/div><\/div><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-38-field-hp\" class=\"wpforms-field-label\">Name<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-38-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"38\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-38\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send Message\" aria-live=\"assertive\" value=\"wpforms-submit\">Send Message<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-02ed74d\" data-id=\"02ed74d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>About the foundation \u00a0\u00a0A leading provider of spare parts, faucets and filters services focused on providing business solutions in gas, petrochemicals, environment, railways, transportation and manufacturing in the Kingdom of Saudi Arabia and the Gulf region. \u00a0We provide professional services with new technology with high standards that guarantee excellence, innovation and customer satisfaction in his &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/proenergiessa.com\/\"> <span class=\"screen-reader-text\">Home<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/proenergiessa.com\/index.php\/wp-json\/wp\/v2\/pages\/159"}],"collection":[{"href":"https:\/\/proenergiessa.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/proenergiessa.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/proenergiessa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/proenergiessa.com\/index.php\/wp-json\/wp\/v2\/comments?post=159"}],"version-history":[{"count":64,"href":"https:\/\/proenergiessa.com\/index.php\/wp-json\/wp\/v2\/pages\/159\/revisions"}],"predecessor-version":[{"id":494,"href":"https:\/\/proenergiessa.com\/index.php\/wp-json\/wp\/v2\/pages\/159\/revisions\/494"}],"wp:attachment":[{"href":"https:\/\/proenergiessa.com\/index.php\/wp-json\/wp\/v2\/media?parent=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}